{"id":4006,"date":"2013-02-06T00:42:04","date_gmt":"2013-02-06T00:42:04","guid":{"rendered":"http:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg"},"modified":"2013-02-06T00:42:04","modified_gmt":"2013-02-06T00:42:04","slug":"wheels_ir_1","status":"inherit","type":"attachment","link":"https:\/\/www.wheelsforwomen.ie\/index.php\/first-drive-citroen-ds3-cabrio\/wheels_ir_1\/","title":{"rendered":"wheels_ir_1"},"author":1,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>wheels_ir_1 - wheelsforwomen.ie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"wheels_ir_1 - wheelsforwomen.ie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"wheelsforwomen.ie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wheelsforwomen\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg\",\"url\":\"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg\",\"name\":\"wheels_ir_1 - wheelsforwomen.ie\",\"isPartOf\":{\"@id\":\"https:\/\/www.wheelsforwomen.ie\/#website\"},\"datePublished\":\"2013-02-06T00:42:04+00:00\",\"dateModified\":\"2013-02-06T00:42:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.wheelsforwomen.ie\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Car Reviews\",\"item\":\"https:\/\/www.wheelsforwomen.ie\/index.php\/category\/new-car-reviews\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"First Drives\",\"item\":\"https:\/\/www.wheelsforwomen.ie\/index.php\/category\/new-car-reviews\/first-drives\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"First Drive &#8211; Citroen DS3 Cabrio\",\"item\":\"https:\/\/www.wheelsforwomen.ie\/index.php\/first-drive-citroen-ds3-cabrio\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"wheels_ir_1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wheelsforwomen.ie\/#website\",\"url\":\"https:\/\/www.wheelsforwomen.ie\/\",\"name\":\"wheelsforwomen.ie\",\"description\":\"Ireland&#039;s only website for women on wheels - cars, motorbikes, bikes\",\"publisher\":{\"@id\":\"https:\/\/www.wheelsforwomen.ie\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wheelsforwomen.ie\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.wheelsforwomen.ie\/#organization\",\"name\":\"wheelsforwomen.ie\",\"url\":\"https:\/\/www.wheelsforwomen.ie\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.wheelsforwomen.ie\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2015\/02\/lwfwogo4.png\",\"contentUrl\":\"http:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2015\/02\/lwfwogo4.png\",\"width\":450,\"height\":60,\"caption\":\"wheelsforwomen.ie\"},\"image\":{\"@id\":\"https:\/\/www.wheelsforwomen.ie\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wheelsforwomen\",\"https:\/\/twitter.com\/wheelsforwomen\",\"https:\/\/www.youtube.com\/channel\/UCCspNSMESDvvavOz4tBrnKw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"wheels_ir_1 - wheelsforwomen.ie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg","og_locale":"en_GB","og_type":"article","og_title":"wheels_ir_1 - wheelsforwomen.ie","og_url":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg","og_site_name":"wheelsforwomen.ie","article_publisher":"https:\/\/www.facebook.com\/wheelsforwomen","og_image":[{"width":600,"height":399,"url":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg","url":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg","name":"wheels_ir_1 - wheelsforwomen.ie","isPartOf":{"@id":"https:\/\/www.wheelsforwomen.ie\/#website"},"datePublished":"2013-02-06T00:42:04+00:00","dateModified":"2013-02-06T00:42:04+00:00","breadcrumb":{"@id":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wheelsforwomen.ie\/"},{"@type":"ListItem","position":2,"name":"Car Reviews","item":"https:\/\/www.wheelsforwomen.ie\/index.php\/category\/new-car-reviews\/"},{"@type":"ListItem","position":3,"name":"First Drives","item":"https:\/\/www.wheelsforwomen.ie\/index.php\/category\/new-car-reviews\/first-drives\/"},{"@type":"ListItem","position":4,"name":"First Drive &#8211; Citroen DS3 Cabrio","item":"https:\/\/www.wheelsforwomen.ie\/index.php\/first-drive-citroen-ds3-cabrio\/"},{"@type":"ListItem","position":5,"name":"wheels_ir_1"}]},{"@type":"WebSite","@id":"https:\/\/www.wheelsforwomen.ie\/#website","url":"https:\/\/www.wheelsforwomen.ie\/","name":"wheelsforwomen.ie","description":"Ireland&#039;s only website for women on wheels - cars, motorbikes, bikes","publisher":{"@id":"https:\/\/www.wheelsforwomen.ie\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wheelsforwomen.ie\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.wheelsforwomen.ie\/#organization","name":"wheelsforwomen.ie","url":"https:\/\/www.wheelsforwomen.ie\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.wheelsforwomen.ie\/#\/schema\/logo\/image\/","url":"http:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2015\/02\/lwfwogo4.png","contentUrl":"http:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2015\/02\/lwfwogo4.png","width":450,"height":60,"caption":"wheelsforwomen.ie"},"image":{"@id":"https:\/\/www.wheelsforwomen.ie\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wheelsforwomen","https:\/\/twitter.com\/wheelsforwomen","https:\/\/www.youtube.com\/channel\/UCCspNSMESDvvavOz4tBrnKw"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg'><img width=\"300\" height=\"199\" src=\"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1-300x199.jpg 300w, https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":399,"file":"2013\/02\/wheels_ir_1.jpg","sizes":{"thumbnail":{"file":"wheels_ir_1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1-150x150.jpg"},"medium":{"file":"wheels_ir_1-300x199.jpg","width":300,"height":199,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1-300x199.jpg"},"yarpp-thumbnail":{"file":"wheels_ir_1-120x120.jpg","width":120,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1-120x120.jpg"},"full":{"file":"wheels_ir_1.jpg","width":600,"height":399,"mime_type":"image\/jpeg","source_url":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":4005,"source_url":"https:\/\/www.wheelsforwomen.ie\/wp\/wp-content\/uploads\/2013\/02\/wheels_ir_1.jpg","_links":{"self":[{"href":"https:\/\/www.wheelsforwomen.ie\/index.php\/wp-json\/wp\/v2\/media\/4006"}],"collection":[{"href":"https:\/\/www.wheelsforwomen.ie\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.wheelsforwomen.ie\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.wheelsforwomen.ie\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wheelsforwomen.ie\/index.php\/wp-json\/wp\/v2\/comments?post=4006"}]}}